{"id":23946,"date":"2016-03-16T19:30:56","date_gmt":"2016-03-16T18:30:56","guid":{"rendered":"https:\/\/zweenhalb.de\/news\/pattern-beech-glued\/"},"modified":"2022-08-09T17:53:16","modified_gmt":"2022-08-09T15:53:16","slug":"pattern-beech-glued","status":"publish","type":"post","link":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/","title":{"rendered":"Pattern beech glued"},"content":{"rendered":"<p>The release sample with the multiplex plate has arrived. Now with compartment for the safety pins.<\/p>\n<p>Then we simulate a barbecue situation right away ;)<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-1279 size-medium\" src=\"http:\/\/grill.philippsack.de\/wp-content\/uploads\/2016\/03\/image-300x169.jpeg\" alt=\"Stainless steel grill\" width=\"300\" height=\"169\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The release sample with the multiplex plate has arrived. Now  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[219],"tags":[1111],"class_list":["post-23946","post","type-post","status-publish","format-standard","hentry","category-grillnews-en","tag-barbecue-situation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pattern beech glued - ZWEEnHALB - der Grill aus Berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"psack\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/\"},\"author\":{\"name\":\"psack\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#\\\/schema\\\/person\\\/cf4b01c3bf7a7279b29800f7b9eada65\"},\"headline\":\"Pattern beech glued\",\"datePublished\":\"2016-03-16T18:30:56+00:00\",\"dateModified\":\"2022-08-09T15:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/\"},\"wordCount\":27,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/grill.philippsack.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/image-300x169.jpeg\",\"keywords\":[\"Barbecue situation\"],\"articleSection\":[\"grillnews\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/\",\"url\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/\",\"name\":\"Pattern beech glued - ZWEEnHALB - der Grill aus Berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/grill.philippsack.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/image-300x169.jpeg\",\"datePublished\":\"2016-03-16T18:30:56+00:00\",\"dateModified\":\"2022-08-09T15:53:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#primaryimage\",\"url\":\"http:\\\/\\\/grill.philippsack.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/image-300x169.jpeg\",\"contentUrl\":\"http:\\\/\\\/grill.philippsack.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/image-300x169.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/pattern-beech-glued\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pattern beech glued\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#website\",\"url\":\"https:\\\/\\\/zweenhalb.de\\\/\",\"name\":\"ZWEEnHALB - der Grill aus Berlin\",\"description\":\"Charcoal grill made of stainless steel for on the road!\",\"publisher\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zweenhalb.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#organization\",\"name\":\"ZWEEnHALB\",\"url\":\"https:\\\/\\\/zweenhalb.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zweenhalb.de\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cropped-zweenhalb-114x114.png\",\"contentUrl\":\"https:\\\/\\\/zweenhalb.de\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cropped-zweenhalb-114x114.png\",\"width\":114,\"height\":114,\"caption\":\"ZWEEnHALB\"},\"image\":{\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zweenhalb.de\\\/#\\\/schema\\\/person\\\/cf4b01c3bf7a7279b29800f7b9eada65\",\"name\":\"psack\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g\",\"caption\":\"psack\"},\"url\":\"https:\\\/\\\/zweenhalb.de\\\/en\\\/news\\\/author\\\/psack\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pattern beech glued - ZWEEnHALB - der Grill aus Berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/","twitter_misc":{"Written by":"psack"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#article","isPartOf":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/"},"author":{"name":"psack","@id":"https:\/\/zweenhalb.de\/#\/schema\/person\/cf4b01c3bf7a7279b29800f7b9eada65"},"headline":"Pattern beech glued","datePublished":"2016-03-16T18:30:56+00:00","dateModified":"2022-08-09T15:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/"},"wordCount":27,"commentCount":0,"publisher":{"@id":"https:\/\/zweenhalb.de\/#organization"},"image":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#primaryimage"},"thumbnailUrl":"http:\/\/grill.philippsack.de\/wp-content\/uploads\/2016\/03\/image-300x169.jpeg","keywords":["Barbecue situation"],"articleSection":["grillnews"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/","url":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/","name":"Pattern beech glued - ZWEEnHALB - der Grill aus Berlin","isPartOf":{"@id":"https:\/\/zweenhalb.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#primaryimage"},"image":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#primaryimage"},"thumbnailUrl":"http:\/\/grill.philippsack.de\/wp-content\/uploads\/2016\/03\/image-300x169.jpeg","datePublished":"2016-03-16T18:30:56+00:00","dateModified":"2022-08-09T15:53:16+00:00","breadcrumb":{"@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#primaryimage","url":"http:\/\/grill.philippsack.de\/wp-content\/uploads\/2016\/03\/image-300x169.jpeg","contentUrl":"http:\/\/grill.philippsack.de\/wp-content\/uploads\/2016\/03\/image-300x169.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/zweenhalb.de\/en\/news\/pattern-beech-glued\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zweenhalb.de\/en\/"},{"@type":"ListItem","position":2,"name":"Pattern beech glued"}]},{"@type":"WebSite","@id":"https:\/\/zweenhalb.de\/#website","url":"https:\/\/zweenhalb.de\/","name":"ZWEEnHALB - der Grill aus Berlin","description":"Charcoal grill made of stainless steel for on the road!","publisher":{"@id":"https:\/\/zweenhalb.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zweenhalb.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zweenhalb.de\/#organization","name":"ZWEEnHALB","url":"https:\/\/zweenhalb.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zweenhalb.de\/#\/schema\/logo\/image\/","url":"https:\/\/zweenhalb.de\/wp-content\/uploads\/2018\/02\/cropped-zweenhalb-114x114.png","contentUrl":"https:\/\/zweenhalb.de\/wp-content\/uploads\/2018\/02\/cropped-zweenhalb-114x114.png","width":114,"height":114,"caption":"ZWEEnHALB"},"image":{"@id":"https:\/\/zweenhalb.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/zweenhalb.de\/#\/schema\/person\/cf4b01c3bf7a7279b29800f7b9eada65","name":"psack","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7d041e5f3b6ec52d1f4dcd0266ccdf14a0b7227561f91f92a474ad68a30da9a?s=96&d=monsterid&r=g","caption":"psack"},"url":"https:\/\/zweenhalb.de\/en\/news\/author\/psack\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/posts\/23946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/comments?post=23946"}],"version-history":[{"count":1,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/posts\/23946\/revisions"}],"predecessor-version":[{"id":23949,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/posts\/23946\/revisions\/23949"}],"wp:attachment":[{"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/media?parent=23946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/categories?post=23946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zweenhalb.de\/en\/wp-json\/wp\/v2\/tags?post=23946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}